{"id":28,"count":7,"description":"","link":"https:\/\/konferenztechnik.de\/es\/dia\/berlin\/","name":"Berl\u00edn","slug":"berlin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/tags\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/posts?tags=28"},{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/jobs?tags=28"},{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/team?tags=28"},{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/lexikon?tags=28"},{"href":"https:\/\/konferenztechnik.de\/es\/wp-json\/wp\/v2\/landingpage?tags=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}