{"id":49500,"date":"2026-02-02T12:45:17","date_gmt":"2026-02-02T11:45:17","guid":{"rendered":"https:\/\/konferenztechnik.de\/?p=49500"},"modified":"2026-02-02T15:14:06","modified_gmt":"2026-02-02T14:14:06","slug":"ptzoptics-move-4k-camera-ptz-4k","status":"publish","type":"post","link":"https:\/\/konferenztechnik.de\/fr\/ptzoptics-move-4k-camera-ptz-4k\/","title":{"rendered":"PTZOptics Move 4K \u2013 Cam\u00e9ra mobile 4K"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"49500\" class=\"elementor elementor-49500\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-59ad04c e-flex e-con-boxed e-con e-parent\" data-id=\"59ad04c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-be8f800 e-flex e-con-boxed e-con e-child\" data-id=\"be8f800\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0afdee1 elementor-widget elementor-widget-heading\" data-id=\"0afdee1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">PTZOptics Move 4K \u2013 la cam\u00e9ra 4K PTZ pour les productions professionnelles en direct<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-80d832c e-grid e-con-boxed e-con e-child\" data-id=\"80d832c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99559f5 elementor-widget elementor-widget-image\" data-id=\"99559f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/PTZO-Kamera-automatisierte-sprecherverfolgung.avif\" class=\"attachment-large size-large wp-image-49501\" alt=\"\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/PTZO-Kamera-automatisierte-sprecherverfolgung.avif 750w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/PTZO-Kamera-automatisierte-sprecherverfolgung-300x300.avif 300w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/PTZO-Kamera-automatisierte-sprecherverfolgung-150x150.avif 150w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/PTZO-Kamera-automatisierte-sprecherverfolgung-12x12.avif 12w\" sizes=\"(max-width: 750px) 100vw, 750px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-477df0c content-align-cta-default elementor-widget elementor-widget-eael-cta-box\" data-id=\"477df0c\" data-element_type=\"widget\" data-widget_type=\"eael-cta-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-call-to-action cta-basic bg-lite cta-preset-1\">\n        <h2 class=\"title eael-cta-heading\">Move 4K<\/h2><p><img decoding=\"async\" class=\"alignnone wp-image-49297\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/01\/neue-konferenztechnik.svg\" alt=\"\" width=\"99\" height=\"99\" title=\"\"><\/p><p>- R\u00e9solution 4K &amp; auto-tracking<\/p><p>- Suivi des personnes<\/p><p>- Forte performance en basse lumi\u00e8re<\/p><p>- NDI\u00ae HX3 &amp; connecteurs flexibles<\/p><p>- Variantes de zoom 12x\/20x\/30x<\/p><p>\u00a0<\/p><a href=\"#kontaktbox\" class=\"cta-button cta-preset-1\">Demander maintenant<\/a>\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-aaa82cd e-flex e-con-boxed e-con e-child\" data-id=\"aaa82cd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b2497 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"c8b2497\" data-element_type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;no_headings_message&quot;:&quot;Es wurden keine \\u00dcberschriften auf dieser Seite gefunden.&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tTable des mati\u00e8res\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__c8b2497\" aria-expanded=\"true\" aria-label=\"Ouvrir la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__c8b2497\" aria-expanded=\"true\" aria-label=\"Fermer la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__c8b2497\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-996ce7d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"996ce7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La PTZOptics Move 4K est une cam\u00e9ra PTZ 4K de derni\u00e8re g\u00e9n\u00e9ration \u2013 dot\u00e9e d'une fonction intelligente d'autotracking, d'options de zoom puissantes et d'une connectivit\u00e9 flexible pour les techniques de conf\u00e9rence modernes, les \u00e9v\u00e9nements hybrides et la diffusion en direct.<\/p><p>\u00a0<\/p><p>Que ce soit dans une salle de conf\u00e9rence, un amphith\u00e9\u00e2tre, une \u00e9glise, un studio ou une application industrielle : Avec la Move 4K, vous automatisez votre r\u00e9gie d'images et obtenez des images tr\u00e8s nettes en qualit\u00e9 UHD.<\/p><p>\u00a0<\/p><p>Nous vous soutenons depuis le choix de la variante appropri\u00e9e jusqu'\u00e0 l'int\u00e9gration dans votre technique m\u00e9diatique existante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b3ddd01 e-flex e-con-boxed e-con e-child\" data-id=\"b3ddd01\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0064566 elementor-widget elementor-widget-heading\" data-id=\"0064566\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PTZOptics Move 4K en un coup d'\u0153il<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74974da elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"74974da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La PTZOptics Move 4K est disponible en trois variantes de zoom : <strong>12x, 20x et 30x<\/strong>. Tous les mod\u00e8les offrent :<\/p><p>\u00a0<\/p><ul><li><strong>R\u00e9solution jusqu'\u00e0 4K @ 60 fps<\/strong> (HDMI\/IP), 1080p @ 60 fps via SDI<\/li><\/ul><ul><li><strong>Auto-tracking intelligent<\/strong> \u2013 Suivre automatiquement des personnes dans l'image<\/li><\/ul><ul><li><strong>Pr\u00e9sentateur Lock\u2122<\/strong>: suivi cibl\u00e9 de certaines personnes, m\u00eame s'il y a plusieurs personnes dans l'image<\/li><\/ul><ul><li><strong>Sorties vid\u00e9o multiples<\/strong>: SDI, HDMI, USB, IP (NDI\u00ae HX3, SRT, RTSP, RTMP)<\/li><\/ul><ul><li><strong>PoE+ (Power over Ethernet)<\/strong>Alimentation et r\u00e9seau par un seul c\u00e2ble<\/li><\/ul><ul><li><strong>Excellentes performances en basse lumi\u00e8re<\/strong> pour les pi\u00e8ces difficilement \u00e9clair\u00e9es<\/li><\/ul><ul><li><strong>5 ans de garantie du fabricant<\/strong> pour une grande s\u00e9curit\u00e9 d'investissement<\/li><\/ul><ul><li><strong>Lampe tally int\u00e9gr\u00e9e<\/strong> \u2013 id\u00e9al pour les configurations de r\u00e9gie et les studios<\/li><\/ul><p>La Move 4K devient ainsi la cam\u00e9ra centrale pour les conf\u00e9rences, les r\u00e9unions, les services religieux, les formations et les productions en direct.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86d6d5b elementor-widget elementor-widget-image\" data-id=\"86d6d5b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse.avif\" class=\"attachment-full size-full wp-image-49502\" alt=\"\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse.avif 1080w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse-300x200.avif 300w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse-1024x683.avif 1024w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse-768x512.avif 768w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/Move-4K-Anschluesse-18x12.avif 18w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39bc999 elementor-widget elementor-widget-heading\" data-id=\"39bc999\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Connexions flexibles et protocoles de streaming modernes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83e8dbc elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"83e8dbc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La PTZOptics Move 4K offre toutes les interfaces courantes afin de s'int\u00e9grer parfaitement dans votre \u00e9quipement de conf\u00e9rence et audiovisuel existant :<\/p><p>\u00a0<\/p><ul><li><strong>HDMI 2.0<\/strong>jusqu'\u00e0 4K @ 60 fps pour les pupitres de r\u00e9gie, les commutateurs matriciels ou les \u00e9crans<\/li><\/ul><ul><li><strong>3G-SDI<\/strong>jusqu'\u00e0 1080p @ 60 fps pour les longues distances de c\u00e2bles dans l'\u00e9v\u00e9nementiel<\/li><\/ul><ul><li><strong>USB 2.0 (Type A)<\/strong>jusqu'\u00e0 4K @ 30 fps, par ex. pour une int\u00e9gration directe dans des syst\u00e8mes de vid\u00e9oconf\u00e9rence<\/li><\/ul><ul><li><strong>Streaming IP<\/strong> via Ethernet avec PoE+ :<\/li><\/ul><ul><li>NDI\u00ae HX3 (int\u00e9gr\u00e9 sans licence)<\/li><\/ul><ul><li>SRT pour des transmissions stables sur des r\u00e9seaux non s\u00e9curis\u00e9s<\/li><\/ul><ul><li>RTSP\/RTMP pour le streaming vers des plateformes comme YouTube ou Facebook<\/li><\/ul><ul><li><strong>entr\u00e9e audio 3,5 mm<\/strong> pour l'int\u00e9gration du son dans les flux SDI, HDMI, USB et IP<\/li><\/ul><p>Le Move 4K est donc une solution id\u00e9ale <strong>Cam\u00e9ra PTZ pour le streaming en direct, les salles de conf\u00e9rence et les \u00e9v\u00e9nements hybrides<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69fb1fd elementor-widget elementor-widget-heading\" data-id=\"69fb1fd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Auto-tracking et Presenter Lock \u2013 moins de personnel, plus de contr\u00f4le<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-84fc135 e-grid e-con-full e-con e-child\" data-id=\"84fc135\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49c81e5 elementor-widget elementor-widget-image\" data-id=\"49c81e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera.avif\" class=\"attachment-full size-full wp-image-49503\" alt=\"\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera.avif 1000w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera-300x300.avif 300w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera-150x150.avif 150w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera-768x768.avif 768w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/sprecher-verfolger-kamera-12x12.avif 12w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a74749b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a74749b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La PTZOptics Move 4K dispose d'un <strong>auto-tracking int\u00e9gr\u00e9<\/strong>, \u2013, qui fonctionne directement dans la cam\u00e9ra, sans PC suppl\u00e9mentaire ni logiciel externe. La cam\u00e9ra reconna\u00eet les locuteurs* dans la pi\u00e8ce, suit leurs mouvements et assure automatiquement un cadrage propre.<\/p><p>\u00a0<\/p><p>Point fort particulier : <strong>Pr\u00e9sentateur Lock\u2122<\/strong><\/p><ul><li>Fixe de mani\u00e8re cibl\u00e9e une personne dans la pi\u00e8ce \u2013 m\u00eame si plusieurs personnes sont dans l'image<\/li><\/ul><ul><li>Id\u00e9al pour les conf\u00e9rences, les sermons, les animations ou les formations<\/li><\/ul><ul><li>Possibilit\u00e9 de passer rapidement d'un locuteur* \u00e0 un autre<\/li><\/ul><p>Ainsi, il est possible de <strong>Conf\u00e9rences, \u00e9v\u00e9nements hybrides et streaming en direct<\/strong> produire de mani\u00e8re fiable, m\u00eame avec des \u00e9quipes r\u00e9duites ou seules.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb93499 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"eb93499\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Montage confortable et int\u00e9gration discr\u00e8te<\/strong><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>La PTZOptics Move 4K peut \u00eatre mont\u00e9e de mani\u00e8re flexible :<\/p><p>\u00a0<\/p><ul><li>montage mural \u00e0 c\u00f4t\u00e9 ou en face de la sc\u00e8ne<\/li><\/ul><ul><li>montage au plafond, par exemple dans les salles de conf\u00e9rence, les amphith\u00e9\u00e2tres ou les \u00e9glises<\/li><\/ul><ul><li>Montage sur des traverses ou des m\u00e2ts dans l'\u00e9v\u00e9nementiel<\/li><\/ul><p>Pratique : la cam\u00e9ra d\u00e9tecte automatiquement la position de montage, <strong>inverse l'image de mani\u00e8re autonome si n\u00e9cessaire<\/strong> et r\u00e9duit ainsi le temps d'installation.<\/p><p>\u00a0<\/p><p>Sur demande, nous fournissons des <strong>Supports muraux, de plafond ou de p\u00f4le<\/strong> ainsi que des bo\u00eetiers de protection pour les environnements exigeants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-744d6e4 elementor-widget elementor-widget-image\" data-id=\"744d6e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"869\" height=\"1400\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum.avif\" class=\"attachment-full size-full wp-image-49504\" alt=\"\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum.avif 869w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum-186x300.avif 186w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum-636x1024.avif 636w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum-768x1237.avif 768w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/wand-deckenmontage-kamera-konferenzraum-7x12.avif 7w\" sizes=\"(max-width: 869px) 100vw, 869px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfbd33d elementor-widget elementor-widget-heading\" data-id=\"cfbd33d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Salle de conf\u00e9rence et \u00e9v\u00e9nement : contr\u00f4ler la cam\u00e9ra avec un smartphone<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-66bdfa5 e-grid e-con-full e-con e-child\" data-id=\"66bdfa5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f29b08b elementor-widget elementor-widget-image\" data-id=\"f29b08b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"854\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/kamera-mit-smartphone-steuern-konferenzraum.avif\" class=\"attachment-full size-full wp-image-49505\" alt=\"\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/kamera-mit-smartphone-steuern-konferenzraum.avif 768w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/kamera-mit-smartphone-steuern-konferenzraum-270x300.avif 270w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/kamera-mit-smartphone-steuern-konferenzraum-11x12.avif 11w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e75f1a elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5e75f1a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Commande simple \u2013 du joystick au logiciel<\/p><p>La PTZOptics Move 4K s'int\u00e8gre dans les flux de travail existants de la technique de conf\u00e9rence et de l'\u00e9v\u00e9nementiel :<\/p><p>\u00a0<\/p><ul><li>Contr\u00f4le par <strong>Manettes de jeu mat\u00e9rielles<\/strong> (par ex. PTZOptics SuperJoy, joysticks IP ou s\u00e9rie)<\/li><\/ul><ul><li>Int\u00e9gration dans <strong>Logiciel de production en direct<\/strong> comme par exemple OBS, vMix, Livestream Studio, TriCaster, etc.<\/li><\/ul><ul><li>Interface web avec une surface claire et des textes d'aide int\u00e9gr\u00e9s<\/li><\/ul><ul><li>Contr\u00f4le par IP, RS-232 ou RS-485 \u2013 adapt\u00e9 \u00e0 votre infrastructure<\/li><\/ul><p>Vous pouvez ainsi contr\u00f4ler le panoramique, l'inclinaison, le zoom, les pr\u00e9s\u00e9lections et l'autotracking dans votre configuration pr\u00e9f\u00e9r\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5fcff7 elementor-widget elementor-widget-heading\" data-id=\"f5fcff7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Id\u00e9al pour les conf\u00e9rences, les \u00e9v\u00e9nements hybrides, les amphith\u00e9\u00e2tres et les salles de s\u00e9minaire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0126caf elementor-cta--skin-cover elementor-cta--valign-bottom elementor-widget elementor-widget-call-to-action\" data-id=\"0126caf\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/konferenztechnik.de\/wp-content\/uploads\/2026\/02\/einfache-bedienung-kamera-fuer-unis.avif);\" role=\"img\" aria-label=\"facile-utilisation-cam\u00e9ra-pour-univers\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-lg\" href=\"#kontaktbox\">\n\t\t\t\t\t\tDemander maintenant\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7458fb0 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"7458fb0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\n<p>La PTZOptics Move 4K est particuli\u00e8rement adapt\u00e9e pour :<\/p>\n<ul>\n<li><strong>Salles de conf\u00e9rence et centres de congr\u00e8s<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>\u00c9v\u00e9nements hybrides et streaming en direct<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Institutions de formation<\/strong> (amphith\u00e9\u00e2tres, salles de s\u00e9minaire)<\/li>\n<\/ul>\n<ul>\n<li><strong>\u00c9glises et maisons de culte<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Entreprises et studios<\/strong> pour webinaires, pr\u00e9sentations de produits, townhalls<\/li>\n<\/ul>\n<ul>\n<li><strong>Industrie et production<\/strong>, pour la documentation, la formation ou la surveillance \u00e0 distance, par exemple<\/li>\n<\/ul>\n<p>En combinaison avec des <strong>Technique de conf\u00e9rence, technique des m\u00e9dias et technique d'interpr\u00e9tation<\/strong> nous cr\u00e9ons avec vous des solutions \u00e9volutives \u2013, de la simple cam\u00e9ra PTZ \u00e0 la salle de conf\u00e9rence ou au studio de streaming enti\u00e8rement \u00e9quip\u00e9.<\/p><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e05f8d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1e05f8d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le PULSE FLEX a <strong class=\"\">pas de batterie int\u00e9gr\u00e9e<\/strong> et sera par d\u00e9faut <strong class=\"\">via un c\u00e2ble d'alimentation (bloc d'alimentation)<\/strong> est exploit\u00e9. Il existe un <strong class=\"\">pack de batteries disponible en option<\/strong>, Le haut-parleur peut \u00eatre utilis\u00e9 de mani\u00e8re portable.<br><br><\/p>\n<p>Pour une utilisation dans des salles de conf\u00e9rence haut de gamme, nous pouvons donc clairement le qualifier de <strong class=\"\">haut-parleurs de conf\u00e9rence fixes, aliment\u00e9s par le secteur<\/strong> repr\u00e9senter \u2013 en option avec extension de batterie, si vous souhaitez mettre l'accent sur la mobilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14cd03c elementor-widget elementor-widget-spacer\" data-id=\"14cd03c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1f6e3c elementor-widget elementor-widget-heading\" data-id=\"e1f6e3c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre avantage avec PCS \u2013 konferenztechnik.de<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5d5df3 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a5d5df3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En tant que partenaire pour <strong>Technique de conf\u00e9rence, technique des m\u00e9dias et technique \u00e9v\u00e9nementielle<\/strong> nous vous assistons tout autour de la PTZOptics Move 4K :<\/p><p>\u00a0<\/p><ul><li>Conseil sur la variante de cam\u00e9ra appropri\u00e9e (12x\/20x\/30x)<\/li><\/ul><ul><li>Planification de l'emplacement des cam\u00e9ras et de l'infrastructure (r\u00e9seau, \u00e9lectricit\u00e9, PoE, chemins de c\u00e2bles)<\/li><\/ul><ul><li>Int\u00e9gration dans des projets existants <strong>Salles de conf\u00e9rence, configurations d'\u00e9v\u00e9nements hybrides et technique AV<\/strong><\/li><\/ul><ul><li>Livraison des <strong>Accessoires<\/strong> (supports, manettes, c\u00e2bles, lecteurs, \u00e9crans)<\/li><\/ul><ul><li>En option : <strong>Installation, mise en service et formation<\/strong> de vos collaborateurs*.<\/li><\/ul><ul><li>Sur demande, concepts pour <strong>\u00e9v\u00e9nements multilingues<\/strong>, y compris technique d'interpr\u00e9tation et streaming<\/li><\/ul><p>N'h\u00e9sitez pas \u00e0 nous demander des options d'achat, de location ou de leasing \u2013 nous trouverons une solution adapt\u00e9e \u00e0 votre budget et \u00e0 votre projet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7548301 elementor-widget elementor-widget-menu-anchor\" data-id=\"7548301\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"kontaktbox\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45399b5 elementor-widget elementor-widget-shortcode\" data-id=\"45399b5\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Avec le Quad-View, l'USB-C tout-en-un, les sorties HDMI doubles et la segmentation de r\u00e9seau int\u00e9gr\u00e9e, le AV Access eShare W90 offre exactement les fonctions qui rendent les r\u00e9unions hybrides modernes plus efficaces et plus claires. <\/p>","protected":false},"author":2,"featured_media":49512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-49500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte"],"acf":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/posts\/49500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/comments?post=49500"}],"version-history":[{"count":11,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/posts\/49500\/revisions"}],"predecessor-version":[{"id":49529,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/posts\/49500\/revisions\/49529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/media\/49512"}],"wp:attachment":[{"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/media?parent=49500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/categories?post=49500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konferenztechnik.de\/fr\/wp-json\/wp\/v2\/tags?post=49500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}