{"id":1562,"date":"2013-08-30T15:08:02","date_gmt":"2013-08-30T13:08:02","guid":{"rendered":"https:\/\/konferenztechnik.de\/?page_id=1562"},"modified":"2013-08-30T15:08:02","modified_gmt":"2013-08-30T13:08:02","slug":"elenco-di-riferimento-evento","status":"publish","type":"page","link":"https:\/\/konferenztechnik.de\/it\/chi-siamo-2\/elenco-di-riferimento-evento\/","title":{"rendered":"Elenco di riferimento dell'evento"},"content":{"rendered":"<h1>Elenco di riferimento dell'evento<\/h1>\n<ul>\n<li>ABB LTD.<\/li>\n<li>Abbott GmbH &amp; Co. KG<\/li>\n<li>Gruppo W\u00fcrth<\/li>\n<li>Gruppo BMW<\/li>\n<li>Associazione degli editori e dei librai tedeschi<\/li>\n<li>Bosch Rexroth AG<\/li>\n<li>Ambasciata degli Stati Uniti d'America<\/li>\n<li>Marketing petrolifero BP<\/li>\n<li>BPW \u2013 Bergische Achsen<\/li>\n<li>Brahms AG<\/li>\n<li>B. Braun Melsungen AG<\/li>\n<li>Associazione federale degli interpreti e dei traduttori (BD\u00dc)<\/li>\n<li>Corte costituzionale federale<\/li>\n<li>Daimler AG<\/li>\n<li>Deichmann<\/li>\n<li>DFB \u2013 Associazione calcistica tedesca e.V.<\/li>\n<li>Fondazione Dieter Schwarz, organizzazione senza scopo di lucro<\/li>\n<li>FIFA \u2013 Federazione Internazionale dell'Associazione Calcio<\/li>\n<li>Fondazione Fritz Thyssen<\/li>\n<li>Fujifilm<\/li>\n<li>DMG Mori Seiki AG<\/li>\n<li>Drees &amp; Sommer AG<\/li>\n<li>Ecolab Germania GmbH<\/li>\n<li>Ford Werke AG<\/li>\n<li>Libera Universit\u00e0 di Berlino<\/li>\n<li>EASA \u2013 Agenzia europea per la sicurezza aerea<\/li>\n<li>GETRAG International GmbH<\/li>\n<li>Camera dell'Artigianato di D\u00fcsseldorf<\/li>\n<li>HeidelbergCement AG<\/li>\n<li>Henry Schein Dental Germany GmbH<\/li>\n<li>Universit\u00e0 di Scienze Applicate di Niederrhein<\/li>\n<li>Hochtief AG<\/li>\n<li>ICG \u2013 Innovation Congress GmbH<\/li>\n<li>IHK D\u00fcsseldorf<\/li>\n<li>Kl\u00f6ckner AG<\/li>\n<li>KPMG<\/li>\n<li>Parlamento statale NRW<\/li>\n<li>Lidl Dienstleistung GmbH &amp; Co. KG<\/li>\n<li>LKA D\u00fcsseldorf<\/li>\n<li>LR Health &amp; Beauty Systems GmbH<\/li>\n<li>Lufthansa Cargo AG<\/li>\n<li>Memoriale e Centro della Memoria di Ravensbr\u00fcck<\/li>\n<li>Metro AG<\/li>\n<li>Nachi Europe GmbH<\/li>\n<li>REWE Zentral AG<\/li>\n<li>Rheinzink GmbH &amp; Co KG<\/li>\n<li>Sachtleben Chemie GmbH<\/li>\n<li>Banca Santander<\/li>\n<li>SCC EVENTS GmbH<\/li>\n<li>Sony Europa<\/li>\n<li>Fluido Sterling<\/li>\n<li>Targobank<\/li>\n<li>Telef\u00f3nica Deutschland Holding AG<\/li>\n<li>TEREX<\/li>\n<li>ThyssenKrupp AG<\/li>\n<li>Unilever Deutschland Holding GmbH<\/li>\n<li>Universit\u00e0 di Heidelberg<\/li>\n<li>Vaillant GmbH<\/li>\n<li>Associazione tedesca dei cementifici<\/li>\n<li>VISTEON Germania GmbH<\/li>\n<li>WINGAS GmbH<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Referenzliste Event ABB AG Abbott GmbH &#038; Co. KG W\u00fcrth Group BMW Group B\u00f6rsenverein des deutschen Buchhandels e.V. Bosch Rexroth AG Botschaft der USA BP Oil Marketing BPW \u2013 Bergische Achsen Brahms AG B. Braun Melsungen AG Bundesverband der Dolmetscher und \u00dcbersetzer e.V. (BD\u00dc) Bundesverfassungsgericht Daimler AG Deichmann DFB \u2013 Deutscher Fu\u00dfball-Bund e.V. Dieter Schwarz [&hellip;]<\/p>","protected":false},"author":1,"featured_media":45482,"parent":12,"menu_order":186,"comment_status":"closed","ping_status":"open","template":"page-right-sidebar.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1562","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/pages\/1562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/comments?post=1562"}],"version-history":[{"count":0,"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/pages\/1562\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/pages\/12"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/media\/45482"}],"wp:attachment":[{"href":"https:\/\/konferenztechnik.de\/it\/wp-json\/wp\/v2\/media?parent=1562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}