{"id":4593,"date":"2014-06-04T10:01:13","date_gmt":"2014-06-04T08:01:13","guid":{"rendered":"https:\/\/konferenztechnik.de\/?p=4593"},"modified":"2023-06-05T12:08:23","modified_gmt":"2023-06-05T10:08:23","slug":"aktualizacje-oprogramowania-sprzetowego-dla-jednostek-bazowych-barco-clickshare","status":"publish","type":"post","link":"https:\/\/konferenztechnik.de\/pl\/aktualizacje-oprogramowania-sprzetowego-dla-jednostek-bazowych-barco-clickshare\/","title":{"rendered":"Aktualizacje oprogramowania sprz\u0119towego dla jednostek bazowych Barco ClickShare"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4593\" class=\"elementor elementor-4593\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-8023111 e-flex e-con-boxed e-con e-parent\" data-id=\"8023111\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b5d752 elementor-widget elementor-widget-heading\" data-id=\"0b5d752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aktualizacje oprogramowania sprz\u0119towego dla jednostek bazowych Barco ClickShare<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10b6033 elementor-widget elementor-widget-image\" data-id=\"10b6033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/barco_clickshare_csm_and_2_buttons1-1024x679.jpg\" class=\"attachment-large size-large wp-image-4595\" alt=\"Barco Clickshare CSM z dwoma przyciskami\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/barco_clickshare_csm_and_2_buttons1-1024x679.jpg 1024w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/barco_clickshare_csm_and_2_buttons1-300x199.jpg 300w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/barco_clickshare_csm_and_2_buttons1-768x509.jpg 768w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/barco_clickshare_csm_and_2_buttons1.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8998b78 elementor-widget elementor-widget-text-editor\" data-id=\"8998b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Opublikowano: 0<span class=\"elementor-post-date\">4.06.2014 <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-552632f e-flex e-con-boxed e-con e-parent\" data-id=\"552632f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-004a3d3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"004a3d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wydano aktualizacje oprogramowania uk\u0142adowego dla jednostek bazowych ClickShare CSC-1 i CSM-1. Oba urz\u0105dzenia otrzyma\u0142y interesuj\u0105ce nowe funkcje i poprawki b\u0142\u0119d\u00f3w. Szczeg\u00f3\u0142owe informacje o zmianach i plikach do pobrania mo\u017cna znale\u017a\u0107 na stronie internetowej Barco pod poni\u017cszymi linkami. Nasz kr\u00f3tki przewodnik pomo\u017ce w procesie aktualizacji.<\/p><p>\u00a0<\/p><p>Wi\u0119cej informacji na temat Barco Clickshare mo\u017cna znale\u017a\u0107 na stronie <a href=\"https:\/\/konferenztechnik.de\/pl\/dystrybucja-technologii-konferencyjnych-i-multimedialnych\/barco-clickshare\/\">na naszych stronach Barco<\/a> lub po prostu zadzwo\u0144 do nas!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1b31b6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a1b31b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2014\/06\/ClickShare-Update_QuickStartGuide-deutsch.pdf\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pobierz ClickShare Update Help jako PDF<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-42f5e9a e-flex e-con-boxed e-con e-parent\" data-id=\"42f5e9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1ee634 elementor-widget elementor-widget-shortcode\" data-id=\"a1ee634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"29098\" class=\"elementor elementor-29098\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-699d0d1a e-flex e-con-boxed e-con e-parent\" data-id=\"699d0d1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11f236ba elementor-widget elementor-widget-post-navigation\" data-id=\"11f236ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Nawigacja wpisu\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/pl\/spojrzenie-za-kulisy\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-left\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M257.5 445.1l-22.2 22.2c-9.4 9.4-24.6 9.4-33.9 0L7 273c-9.4-9.4-9.4-24.6 0-33.9L201.4 44.7c9.4-9.4 24.6-9.4 33.9 0l22.2 22.2c9.5 9.5 9.3 25-.4 34.3L136.6 216H424c13.3 0 24 10.7 24 24v32c0 13.3-10.7 24-24 24H136.6l120.5 114.8c9.8 9.3 10 24.8.4 34.3z\"><\/path><\/svg><span class=\"elementor-screen-only\">Prev<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Poprzedni<\/span><span class=\"post-navigation__prev--title\">Spojrzenie za kulisy<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/pl\/strumieniowe-przesylanie-dzwieku-przez-wi-fi-do-smartfona\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Nast\u0119pny<\/span><span class=\"post-navigation__next--title\">Strumieniowe przesy\u0142anie d\u017awi\u0119ku przez WLAN do smartfona<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><span class=\"elementor-screen-only\">Nast\u0119pny<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81a2b13 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"81a2b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/pl\/wiadomosci\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5a27b650-727a-4659-9d92-75e42c38903b\" viewbox=\"0 0 19.67 14.54\"><g id=\"uuid-40aca98c-811b-43af-9bb7-b3a092d9bdfe\"><rect x=\".03\" width=\"6\" height=\"6\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"6.85\" width=\"6\" height=\"7.65\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"13.67\" width=\"6\" height=\"6.51\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect y=\"7\" width=\"6\" height=\"7.55\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"13.64\" y=\"7.22\" width=\"6\" height=\"7.33\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"6.82\" y=\"8.54\" width=\"6\" height=\"6\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Firmware Updates f\u00fcr Barco ClickShare Base Units Ver\u00f6ffentlicht: 04.06.2014 F\u00fcr die ClickShare Base Units CSC-1 und CSM-1 wurden Firmware Updates ver\u00f6ffentlicht. Beide Ger\u00e4te erhalten interessante neue Funktionen sowie Bugfixes. Genaue Informationen \u00fcber die \u00c4nderungen sowie die Dateien zum Download finden Sie auf der Website von Barco unter den unten stehenden Links. In unserer Kurzanleitung finden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/posts\/4593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/comments?post=4593"}],"version-history":[{"count":0,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/posts\/4593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/media\/29741"}],"wp:attachment":[{"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/media?parent=4593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/categories?post=4593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konferenztechnik.de\/pl\/wp-json\/wp\/v2\/tags?post=4593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}