{"id":9324,"date":"2017-03-08T10:55:06","date_gmt":"2017-03-08T09:55:06","guid":{"rendered":"https:\/\/www.konferenztechnik.de\/?post_type=lexikon_eintrag&#038;p=9324\/"},"modified":"2023-08-08T13:46:34","modified_gmt":"2023-08-08T11:46:34","slug":"%e5%b7%a5%e8%89%ba%e5%b7%a5%e7%a8%8b%e5%ad%a6%e6%a0%a1","status":"publish","type":"lexikon","link":"https:\/\/konferenztechnik.de\/zh\/%e8%af%8d%e5%85%b8\/%e5%b7%a5%e8%89%ba%e5%b7%a5%e7%a8%8b%e5%ad%a6%e6%a0%a1\/","title":{"rendered":"\u5b66\u6821 \u6d3b\u52a8\u6280\u672f"},"content":{"rendered":"<h1>\u5b66\u6821\u6d3b\u52a8\u6280\u672f \u2013 \u57f9\u8bad\u5730\u5740<\/h1>\n<p>\u4ee5\u4e0b\u5b66\u6821\u76ee\u524d\u6b63\u5728\u63d0\u4f9b\u6d3b\u52a8\u6280\u672f\u4e13\u5bb6\u57f9\u8bad\uff1a<\/p>\n<ul>\n<li>\u804c\u4e1a\u5b66\u6821\u3001<br \/>\n\u901a\u4fe1\u5de5\u7a0b\u9ad8\u7ea7\u57f9\u8bad\u4e2d\u5fc3<br \/>\n\u5965\u65af\u9646\u8857 23-32 \u53f7<br \/>\n<b>13359 \u67cf\u6797<\/b><br \/>\n\u7535\u8bdd\uff1a(0 30) 45 75 75-10<\/li>\n<li>\u897f\u95e8\u5b50 SIB \u804c\u4e1a\u57f9\u8bad<br \/>\n\u6d3b\u52a8\u6280\u672f\u4e13\u5bb6<br \/>\n<b>13629 \u67cf\u6797<\/b><br \/>\n\u7535\u8bdd\uff1a(0 30) 3 89 44 67<\/li>\n<li>\u6cd5\u59c6\u68ee\u804c\u4e1a\u5b66\u6821 G 16<br \/>\nHermelinweg 8<br \/>\n<b>22159 \u6c49\u5821<\/b><br \/>\n\u7535\u8bdd\uff1a(0 40) 68 89 47 35<\/li>\n<li>\u804c\u4e1a\u5b66\u6821 4<br \/>\n\u7535\u6c14\u5de5\u7a0b<br \/>\n\u53e4\u65af\u5854\u592b-\u5e03\u62c9\u514b\u5927\u8857 1 \u53f7<br \/>\n<b>30169 \u6c49\u8bfa\u5a01<\/b><br \/>\n\u7535\u8bdd\uff1a(05 11) 16 84-51 53<\/li>\n<li>\u804c\u4e1a\u5b66\u6821<br \/>\n\u5de5\u4e1a\u5b66\u6821 1<br \/>\n\u5e03\u5415\u683c\u66fc\u5927\u8857 29 \u53f7<br \/>\n<b>44135 \u591a\u7279\u8499\u5fb7<\/b><br \/>\n\u7535\u8bdd\uff1a(02 31) 5 02 31 46<\/li>\n<li>\u6280\u672f\u804c\u4e1a\u5b66\u6821<br \/>\n\u6717\u5e93\u9ed8\u7530\u95f4\u5c0f\u8def<br \/>\n<b>49661 Cloppenburg<\/b><br \/>\n\u7535\u8bdd\uff1a(0 44 71) 94 95-0<\/li>\n<li><a href=\"https:\/\/www.gso-koeln.de\/\" target=\"_new\" rel=\"noopener\">\u4e54\u6cbb-\u897f\u8499-\u6b27\u59c6\u5b66\u6821<\/a><br \/>\n\u897f\u74e6\u5c14\u5fb7\u5927\u8857 92 \u53f7<br \/>\n<b>51105 \u79d1\u9686<\/b><br \/>\n\u7535\u8bdd\uff1a(02 21) 8 39 13-20<\/li>\n<li>\u804c\u4e1a\u5b66\u6821 I<br \/>\n\u8d38\u6613\u548c\u6280\u672f<br \/>\nAm Judensand 12<br \/>\n<b>55122 \u7f8e\u56e0\u8328<\/b><br \/>\n\u7535\u8bdd\uff1a(0 61 31) 37 26 64<\/li>\n<li>\u5f17\u91cc\u5fb7\u91cc\u5e0c-\u57c3\u4f2f\u7279\u5b66\u6821<br \/>\n\u5e03\u4f26\u5e0c\u5c14\u767b\u5927\u8857 53 \u53f7<br \/>\n<b>65189 \u5a01\u65af\u5df4\u767b<\/b><br \/>\n\u7535\u8bdd\uff1a(06 11) 31 52-10<\/li>\n<li>\u5df4\u767b-\u5df4\u767b\u8d38\u6613\u5b66\u6821<br \/>\n\u6d3b\u52a8\u6280\u672f\u4e13\u5bb6<br \/>\n\u5df4\u5c14\u683c\u5927\u8857 15 \u53f7<br \/>\n<b>76532 \u5df4\u767b\u5df4\u767b<\/b><br \/>\n\u7535\u8bdd\uff1a(0 72 21) 93 19 46<\/li>\n<li>\u5de5\u4e1a\u7535\u5b50\u804c\u4e1a\u5b66\u6821<br \/>\n\u4f2f\u683c\u68ee\u5927\u8857 109 \u53f7<br \/>\n<b>81245 \u6155\u5c3c\u9ed1<\/b><br \/>\n\u7535\u8bdd\uff1a(0 89) 23 33 44 42<\/li>\n<li>\u5b89\u5fb7\u70c8\u4e9a\u65af-\u6208\u767b\u5b66\u6821<br \/>\nWeidengasse 8<br \/>\n<b>99048 \u57c3\u5c14\u798f\u7279<\/b><br \/>\n\u7535\u8bdd\uff1a(03 61) 55 80 70<\/li>\n<\/ul>\n<p>\u60a8\u4e5f\u53ef\u4ee5\u8054\u7cfb\u5f53\u5730\u7684\u5de5\u5546\u4f1a\uff08IHK\uff09\u4e86\u89e3\u66f4\u591a\u4fe1\u606f\u3002<\/p>\n<p>\u4ee5\u4e0b\u673a\u6784\u4e5f\u5f88\u4e50\u610f\u4e3a\u60a8\u63d0\u4f9b\u5e2e\u52a9\uff1a<\/p>\n<ul>\n<li>DTHG \u5fb7\u56fd\u620f\u5267\u6280\u672f\u534f\u4f1a<br \/>\n\u683c\u9c81\u4f2f\u8857 76 \u53f7<br \/>\n85586 \u6ce2\u6069<br \/>\n\u7535\u8bdd\uff1a(0 81 21) 7 65 31<br \/>\n\u7535\u5b50\u90ae\u4ef6\uff1acentrale@dthg.de<\/li>\n<li>VPLT \u4e13\u4e1a\u706f\u5149\u4e0e\u97f3\u54cd\u6280\u672f\u534f\u4f1a e.V.<br \/>\n\u74e6\u5c14\u65af\u7f57\u5fb7\u8857 159 \u53f7<br \/>\n30853 \u5170\u6839\u54c8\u6839\/\u6c49\u8bfa\u5a01<br \/>\n\u7535\u8bdd\uff1a(05 11) 9 66 68 89<br \/>\n\u7535\u5b50\u90ae\u4ef6\uff1ainfo@vplt.org<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Schulen Veranstaltungstechnik &#8211; Adressen zur Ausbildung Eine Ausbildung zur &#8222;Fachkraft f\u00fcr Veranstaltungstechnik&#8220; wird zur Zeit durch folgende Schulen begleitet: Berufsfachschule, Oberstufenzentrum Nachrichtentechnik Osloer Stra\u00dfe 23-32 13359 Berlin Telefon: (0 30) 45 75 75-10 Siemens SIB Berufsausbildung Fachkraft f\u00fcr Veranstaltungstechnik 13629 Berlin Telefon: (0 30) 3 89 44 67 Berufliche Schule Farmsen G 16 Hermelinweg 8 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":45482,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-9324","lexikon","type-lexikon","status-publish","format-standard","has-post-thumbnail","hentry","category-lexikon"],"acf":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/lexikon\/9324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/lexikon"}],"about":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/types\/lexikon"}],"author":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/lexikon\/9324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/media\/45482"}],"wp:attachment":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/media?parent=9324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/categories?post=9324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/tags?post=9324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}