{"id":16551,"date":"2020-10-30T09:42:30","date_gmt":"2020-10-30T08:42:30","guid":{"rendered":"https:\/\/www.konferenztechnik.de\/?p=16551"},"modified":"2023-06-07T13:28:35","modified_gmt":"2023-06-07T11:28:35","slug":"%e7%94%b5%e6%99%95%e6%97%b6%e4%bb%a3%e7%9a%84%e4%bc%9a%e8%ae%ae","status":"publish","type":"post","link":"https:\/\/konferenztechnik.de\/zh\/%e7%94%b5%e6%99%95%e6%97%b6%e4%bb%a3%e7%9a%84%e4%bc%9a%e8%ae%ae\/","title":{"rendered":"\u79d1\u7f57\u7eb3\u65f6\u4ee3\u7684\u4f1a\u8bae"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16551\" class=\"elementor elementor-16551\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1f5bfb6 e-flex e-con-boxed e-con e-parent\" data-id=\"1f5bfb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab8b4e elementor-widget elementor-widget-heading\" data-id=\"2ab8b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5728\u65e5\u5195\u65f6\u671f\u5b89\u5168\u7ec4\u7ec7\u6d3b\u52a8\u548c\u4f1a\u8bae<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e7fd54 elementor-widget elementor-widget-image\" data-id=\"5e7fd54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"773\" height=\"404\" src=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2020\/10\/Hybride-Events-in-Zeiten-von-corona-e1604057178693.jpg\" class=\"attachment-large size-large wp-image-16561\" alt=\"\u5728\u79d1\u7f57\u7eb3\u53ec\u5f00\u4f1a\u8bae\" srcset=\"https:\/\/konferenztechnik.de\/wp-content\/uploads\/2020\/10\/Hybride-Events-in-Zeiten-von-corona-e1604057178693.jpg 773w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2020\/10\/Hybride-Events-in-Zeiten-von-corona-e1604057178693-300x157.jpg 300w, https:\/\/konferenztechnik.de\/wp-content\/uploads\/2020\/10\/Hybride-Events-in-Zeiten-von-corona-e1604057178693-768x401.jpg 768w\" sizes=\"(max-width: 773px) 100vw, 773px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-696f22c elementor-widget elementor-widget-text-editor\" data-id=\"696f22c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u51fa\u7248\u65e5\u671f\uff1a2020 \u5e74 10 \u6708 30 \u65e5<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-352e4a7 e-flex e-con-boxed e-con e-parent\" data-id=\"352e4a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce5df4d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ce5df4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u6709\u5173\u5404\u79cd\u4f1a\u8bae\u548c\u6d3b\u52a8\u7684\u6700\u65b0\u4fe1\u606f<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81a4211 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"81a4211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u76ee\u524d\uff0c\u60a8\u53ef\u4ee5\u4e3e\u529e\u4f1a\u8bae\u548c\u5546\u52a1\u4f1a\u8bae\u3002\u4f46\u4e0e\u79c1\u4eba\u805a\u4f1a\u4e0d\u540c\u3002\u4f8b\u5982\uff0c\u5728\u67cf\u6797\uff0c\u4ecd\u7136\u53ef\u4ee5\u4e3e\u529e\u4e0d\u8d85\u8fc7 50 \u4eba\u7684\u5ba4\u5916\u6d3b\u52a8\u548c\u4e0d\u8d85\u8fc7 20 \u4eba\u7684\u5ba4\u5185\u6d3b\u52a8\uff08\u622a\u81f3 2021 \u5e74 1 \u6708 24 \u65e5\uff09\u3002<\/p><p>\u6211\u4eec\u5f88\u4e50\u610f\u4e3a\u60a8\u7684\u6d3b\u52a8\u6784\u601d\u63d0\u4f9b\u652f\u6301\uff0c\u5e76\u4e0e\u60a8\u4e00\u8d77\u4e3a\u60a8\u7684\u6d3b\u52a8\u5bfb\u627e\u5408\u9002\u7684\u89e3\u51b3\u65b9\u6848\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467fd67 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"467fd67\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u6570\u5b57\u4f1a\u8bae\u3001\u6df7\u5408\u6d3b\u52a8\u3001\u6d41\u5a92\u4f53\u548c\u89c6\u9891\u4f1a\u8bae<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1521480 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1521480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u6570\u5b57\u6d3b\u52a8\u548c\u4f1a\u8bae\u4e3a\u4f1a\u8bae\u3001\u4ea4\u6d41\u5185\u5bb9\u3001\u5168\u7403\u8054\u7f51\u4ee5\u53ca\u7ec4\u7ec7\u548c\u4fdd\u6301\u4e0e\u5ba2\u6237\u3001\u4e1a\u52a1\u4f19\u4f34\u548c\u5458\u5de5\u7684\u751f\u52a8\u4ea4\u6d41\u63d0\u4f9b\u4e86\u4ee4\u4eba\u5174\u594b\u7684\u673a\u4f1a\u3002<\/p><p>\u91cd\u8981\u7684\u4f1a\u8bae\u548c\u5c4a\u4f1a\u4e5f\u53ef\u4ee5\u901a\u8fc7\u6570\u5b57\u6216\u6df7\u5408\u5f62\u5f0f\u5408\u6cd5\u4e3e\u884c\u3002\u80a1\u4e1c\u4f1a\u8bae\u3001\u9996\u5e2d\u6267\u884c\u5b98\u4f1a\u8bae\u3001\u5de5\u4f5c\u59d4\u5458\u4f1a\u4f1a\u8bae\u3001\u8bae\u4f1a\u8ba8\u8bba\u548c\u5176\u4ed6\u5fc5\u8981\u7684\u4f1a\u8bae\u90fd\u53ef\u4ee5\u8f7b\u677e\u5730\u4ee5\u6570\u5b57\u5f62\u5f0f\u4e3e\u884c\u3002\u89c6\u9891\u4f1a\u8bae\u53ef\u5c06\u516c\u53f8\u529e\u516c\u5ba4\u4e0e\u516c\u53f8\u603b\u90e8\u8fde\u63a5\u8d77\u6765\uff0c\u6216\u4e0e\u5728\u5bb6\u5de5\u4f5c\u7684\u5458\u5de5\u4e3e\u884c\u4f1a\u8bae\u3002\u5e26\u6709\u540c\u58f0\u4f20\u8bd1\u529f\u80fd\u7684\u591a\u8bed\u79cd\u89e3\u51b3\u65b9\u6848\u6709\u52a9\u4e8e\u53ec\u5f00\u56fd\u9645\u4f1a\u8bae\u3002<\/p><p>\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u627e\u5230\u6709\u5173\u6d3b\u52a8\u5f62\u5f0f\u548c\u6240\u4f7f\u7528\u6280\u672f\u7684\u66f4\u591a\u4fe1\u606f<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60989ed elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"60989ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e6%b7%b7%e5%90%88%e6%b4%bb%e5%8a%a8\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u6df7\u5408\u6d3b\u52a8<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e8%a7%86%e9%a2%91%e4%bc%9a%e8%ae%ae%e7%a7%9f%e7%94%a8%e6%8a%80%e6%9c%af%e5%92%8c%e6%9c%8d%e5%8a%a1\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u89c6\u9891\u4f1a\u8bae\uff1a\u6280\u672f\u4e0e\u670d\u52a1<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e8%bf%9c%e7%a8%8b%e5%8f%a3%e8%af%91-2\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u8fdc\u7a0b\u53e3\u8bd1<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e7%a7%9f%e8%b5%81%e6%b5%81%e5%aa%92%e4%bd%93%e6%8a%80%e6%9c%af\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u79df\u8d41\u6d41\u5a92\u4f53\u6280\u672f<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e4%bc%9a%e8%ae%ae%e8%ae%be%e5%a4%87%e7%a7%9f%e8%b5%81\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u4f1a\u8bae\u6280\u672f\u79df\u7528<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b763f49 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b763f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u89c6\u9891\u4f1a\u8bae\u3001\u6570\u5b57\u4f1a\u8bae\u548c\u6df7\u5408\u6d3b\u52a8\u7684\u6570\u636e\u4fdd\u62a4<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ae5cf1 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"8ae5cf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PCS GmbH \u5728\u5fb7\u56fd\u7684\u6570\u636e\u4e2d\u5fc3\u8fd0\u8425\u81ea\u5df1\u7684\u89c6\u9891\u4f1a\u8bae\u670d\u52a1\u5668\u3002\u8fd9\u610f\u5473\u7740\u654f\u611f\u6570\u636e\u4e0d\u4f1a\u79bb\u5f00\u6b27\u76df\u9886\u571f\uff0c\u5e76\u6309\u7167 GDPR \u8fdb\u884c\u5904\u7406\u3002\u7531\u4e8e\u6211\u4eec\u4f4d\u4e8e\u5fb7\u56fd\uff0c\u60a8\u7684\u6570\u636e\u53d7\u5230\u66f4\u4e3a\u4e25\u683c\u7684\u300a\u5fb7\u56fd\u6570\u636e\u4fdd\u62a4\u6cd5\u300b\u7684\u4fdd\u62a4\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a2840e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9a2840e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u536b\u751f\u6982\u5ff5\u7684\u7ec4\u6210\u90e8\u5206<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d43f70b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"d43f70b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u6211\u4eec\u7684\u9879\u76ee\u89c4\u5212\u4eba\u5458\u5f88\u4e50\u610f\u4e3a\u60a8\u7684\u6d3b\u52a8\u5236\u5b9a\u536b\u751f\u6982\u5ff5\u3002\u6211\u4eec\u7684\u821e\u53f0\u548c\u6d3b\u52a8\u6280\u672f\u4e13\u5bb6\u6709\u6743\u5728\u73b0\u573a\u5b9e\u65bd\u548c\u76d1\u63a7\u8fd9\u4e9b\u6982\u5ff5\u3002<\/p><div class=\"spacer\">\u00a0<\/div><p>\u536b\u751f\u6982\u5ff5\u81f3\u5c11\u5e94\u5305\u542b\u4ee5\u4e0b\u5185\u5bb9<\/p><ul><li>\u6d3b\u52a8\u8bf4\u660e\uff0c\u5305\u62ec\u5185\u5bb9\u3001\u7a7a\u95f4\u548c\u65f6\u95f4\u5b89\u6392<\/li><li>\u4ece\u536b\u751f\u89d2\u5ea6\u8fdb\u884c\u98ce\u9669\u8bc4\u4f30<\/li><li>\u63aa\u65bd\u7684\u5b9a\u4e49<\/li><li>\u6e05\u6d01\u548c\u6d88\u6bd2\u8ba1\u5212<\/li><li>\u536b\u751f\u63aa\u65bd\u5de5\u4f5c\u6307\u5357<\/li><li>\u5fc5\u8981\u6307\u793a\u7684\u5b9a\u4e49<\/li><\/ul><p>(\u6765\u6e90\uff1a\u67cf\u6797\u65c5\u6e38\u5c40\uff09<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f6207b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6f6207b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u6709\u5173\u79d1\u7f57\u5a1c\u65f6\u4ee3\u4f1a\u8bae\u4e3b\u9898\u7684\u94fe\u63a5\u96c6<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-835792c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"835792c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u627e\u5230\u67cf\u6797\u3001\u6155\u5c3c\u9ed1\u3001\u675c\u585e\u5c14\u591a\u592b\u548c\u6d77\u5c14\u5e03\u9686\u7b49\u57ce\u5e02\u7684\u6700\u65b0\u6d3b\u52a8\u6307\u5357\u3002<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abe3ef1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"abe3ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u67cf\u6797<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8a0dd4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f8a0dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.berlin.de\/corona\/massnahmen\/veranstaltungen-und-kultur\/\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u67cf\u6797\u7684\u6d3b\u52a8\u63aa\u65bd<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.berlin.de\/corona\/massnahmen\/verordnung\/\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u67cf\u6797 SARS-CoV-2 \u611f\u67d3\u9632\u62a4\u6761\u4f8b<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-922195a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"922195a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u6155\u5c3c\u9ed1<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24faa45 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"24faa45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.corona-katastrophenschutz.bayern.de\/faq\/index.php\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u5df4\u4f10\u5229\u4e9a\u51a0\u72b6\u75c5\u6bd2\u4fe1\u606f<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-932d250 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"932d250\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u675c\u585e\u5c14\u591a\u592b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e795b4c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e795b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.land.nrw\/de\/wichtige-fragen-und-antworten-zum-corona-virus\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u5173\u4e8e\u5317\u5a01\u5dde\u7535\u6655\u7684\u5e38\u89c1\u95ee\u9898<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99ab9d7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"99ab9d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u6d77\u5c14\u5e03\u9686<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69df368 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"69df368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.heilbronn.de\/local-storage-stadt-heilbronn\/coronavirus\/informationen-zum-coronavirus.html\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u6d77\u5c14\u5e03\u9686\u51a0\u72b6\u75c5\u6bd2\u4fe1\u606f<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f825782 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f825782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u5173\u4e8e\u79d1\u7f57\u5a1c\u65f6\u4ee3\u6d3b\u52a8\u7ba1\u7406\u4e3b\u9898\u7684\u95ee\u9898\u96c6<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19fdaff elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"19fdaff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/convention.visitberlin.de\/restartBerlin\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u79d1\u7f57\u5a1c\u65f6\u4ee3\u7684\u6d3b\u52a8\u7ba1\u7406<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3fe861a e-flex e-con-boxed e-con e-parent\" data-id=\"3fe861a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-111dd92 elementor-widget elementor-widget-shortcode\" data-id=\"111dd92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"29098\" class=\"elementor elementor-29098\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-699d0d1a e-flex e-con-boxed e-con e-parent\" data-id=\"699d0d1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11f236ba elementor-widget elementor-widget-post-navigation\" data-id=\"11f236ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"\u90ae\u653f\u5bfc\u822a\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e6%89%80%e6%9c%89-pcs-%e5%88%86%e9%83%a8%e7%8e%b0%e5%9c%a8%e9%83%bd%e5%8f%af%e6%8f%90%e4%be%9b%e8%bf%9c%e7%a8%8b%e5%8f%a3%e8%af%91%e6%9c%8d%e5%8a%a1\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-left\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M257.5 445.1l-22.2 22.2c-9.4 9.4-24.6 9.4-33.9 0L7 273c-9.4-9.4-9.4-24.6 0-33.9L201.4 44.7c9.4-9.4 24.6-9.4 33.9 0l22.2 22.2c9.5 9.5 9.3 25-.4 34.3L136.6 216H424c13.3 0 24 10.7 24 24v32c0 13.3-10.7 24-24 24H136.6l120.5 114.8c9.8 9.3 10 24.8.4 34.3z\"><\/path><\/svg><span class=\"elementor-screen-only\">\u4e0a\u4e00\u9875<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">\u4e0a\u4e00\u9875<\/span><span class=\"post-navigation__prev--title\">\u6240\u6709 PCS \u5206\u90e8\u73b0\u5728\u90fd\u53ef\u63d0\u4f9b\u8fdc\u7a0b\u53e3\u8bd1\u670d\u52a1<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/konferenztechnik.de\/zh\/%e6%ac%a7%e6%b4%b2%e4%bc%9a%e8%ae%ae%e5%8f%a3%e8%af%91%e7%bd%91%e7%bb%9c%e7%a0%94%e8%ae%a8%e4%bc%9a\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">\u4e0b\u4e00\u9875<\/span><span class=\"post-navigation__next--title\">\u6b27\u6d32\u4f1a\u8bae\u53e3\u8bd1\u7f51\u7edc\u7814\u8ba8\u4f1a<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><span class=\"elementor-screen-only\">\u4e0b\u4e00\u9875<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81a2b13 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"81a2b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/zh\/%e6%96%b0%e9%97%bb\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5a27b650-727a-4659-9d92-75e42c38903b\" viewbox=\"0 0 19.67 14.54\"><g id=\"uuid-40aca98c-811b-43af-9bb7-b3a092d9bdfe\"><rect x=\".03\" width=\"6\" height=\"6\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"6.85\" width=\"6\" height=\"7.65\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"13.67\" width=\"6\" height=\"6.51\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect y=\"7\" width=\"6\" height=\"7.55\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"13.64\" y=\"7.22\" width=\"6\" height=\"7.33\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><rect x=\"6.82\" y=\"8.54\" width=\"6\" height=\"6\" rx=\"2\" ry=\"2\" style=\"fill:currentColor\"><\/rect><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Events, Veranstaltungen und Konferenzen in Zeiten von Corona sicher durchf\u00fchren Ver\u00f6ffentlicht: 30.10.2020 Aktuelle Informationen zu Konferenzen, Meetings und Events Sie k\u00f6nnen aktuell Konferenzen und gesch\u00e4ftliche Meetings durchf\u00fchren. Es gelten andere Richtlinien als f\u00fcr private Feiern. In Berlin sind z. B. nach wie vor Veranstaltungen im Freien mit bis zu 50 Teilnehmern und in geschlossenen R\u00e4umen [&hellip;]<\/p>","protected":false},"author":1,"featured_media":27341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-16551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/posts\/16551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/comments?post=16551"}],"version-history":[{"count":0,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/posts\/16551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/media\/27341"}],"wp:attachment":[{"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/media?parent=16551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/categories?post=16551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konferenztechnik.de\/zh\/wp-json\/wp\/v2\/tags?post=16551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}